{"id":4280,"date":"2021-10-25T13:09:59","date_gmt":"2021-10-25T11:09:59","guid":{"rendered":"https:\/\/ccaves.org\/blog\/?p=4280"},"modified":"2023-09-04T15:40:36","modified_gmt":"2023-09-04T13:40:36","slug":"medias-photovoltaique-causse-comtal","status":"publish","type":"post","link":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/","title":{"rendered":"medias photovolta\u00efque causse comtal"},"content":{"rendered":"<h1 style=\"text-align: center;\"><strong>Articles du collectif ou articles \u00e9crits par nos membres<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong> ou pour lesquels ils ont particip\u00e9<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/la-trousse-correzienne.org\/\"><strong>La Trousse Corr\u00e9zienne<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&#8230;&#8230;&#8230;&#8230;..<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"\" title=\"Agrivolta\u00efsme. Ne tombons pas dans le panneau\u00a0!\"> <a title=\"Afficher la couverture\" href=\"https:\/\/www.revuesilence.net\/IMG\/rubon510.jpg?1690208310\"><img loading=\"lazy\" decoding=\"async\" class=\"spip_logo spip_logos aligncenter\" src=\"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201\" alt=\"\" width=\"425\" height=\"600\" \/><\/a> <\/span><\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/www.revuesilence.net\/numeros\/524-Agrivoltaisme-Ne-tombons-pas-dans-le-panneau\/\">https:\/\/www.revuesilence.net\/numeros\/524-Agrivoltaisme-Ne-tombons-pas-dans-le-panneau\/<\/a><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&#8230;&#8230;&#8230;&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Le Soleil se l\u00e8ve \u00e0 l&rsquo;ouest,<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong> dossier du Canard Enchain\u00e9, avril 2023<\/strong><\/h1>\n<p style=\"text-align: center;\">pages 1-2<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Canard-dossier-PV-avril-2023-scaled.jpg\">https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Canard-dossier-PV-avril-2023-scaled.jpg<\/a><\/p>\n<p style=\"text-align: center;\">pages 3-4<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/canrd-pv-avril-23-2--scaled.jpg\">https:\/\/ccaves.org\/blog\/wp-content\/uploads\/canrd-pv-avril-23-2&#8211;scaled.jpg<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&#8230;&#8230;&#8230;&#8230;..<\/p>\n<h1><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Nat-et-progres26-28.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Revue Nature et Progr\u00e8s, printemps 2023 <\/strong><\/a><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Nat-et-progres26-28.pdf\" target=\"_blank\" rel=\"noopener\"><strong>\u00ab\u00a0Contre l&rsquo; agrivolta\u00efsme, l&rsquo;autonomie paysanne\u00a0\u00bb<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\">&#8230;&#8230;.<\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Biocontact, avril 2023<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong>\u00ab\u00a0L&rsquo;agrivolta\u00efsme, une aberration\u00a0\u00bb<\/strong><\/h1>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/page1.pdf\" target=\"_blank\" rel=\"noopener\">page 1<\/a><\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/page2.pdf\" target=\"_blank\" rel=\"noopener\">page 2<\/a><\/h2>\n<h1><\/h1>\n<h1 style=\"text-align: center;\"><strong>&#8230;&#8230;&#8230;<\/strong><\/h1>\n<p>&nbsp;<\/p>\n<h1 class=\"page-title\" style=\"text-align: center;\"><a href=\"https:\/\/www.sudouest.fr\/pyrenees-atlantiques\/oloron-sainte-marie\/projet-de-photovoltaique-en-bearn-nous-ne-sommes-pas-des-cultivateurs-de-kilowatts-denonce-la-confederation-paysanne-14125560.php\" target=\"_blank\" rel=\"noopener\">Projet photovolta\u00efque en B\u00e9arn : \u00ab Nous ne sommes pas des cultivateurs de kilowatts \u00bb, d\u00e9nonce la Conf\u00e9d\u00e9ration Paysanne. Sud-Ouest le 20\/02\/2023<\/a><\/h1>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/sud-ouest-article-conference-barnjpdf.pdf\" target=\"_blank\" rel=\"noopener\">Lire ici le texte<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&#8230;&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/agrivoltaisme-canard-ench8022023.pdf\" target=\"_blank\" rel=\"noopener\">Une agriculture survolt\u00e9e,<\/a><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/agrivoltaisme-canard-ench8022023.pdf\"> Le Canard Enchaine 8 f\u00e9vrier 2023<\/a><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/lagedefaire-lejournal.fr\/pour-un-autre-photovoltaique\/\"><strong>L&rsquo;Age de Faire, dossier sur le PV, janvier 2023<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"http:\/\/www.zinzine.domainepublic.net\/?ref=7730\" target=\"_blank\" rel=\"noopener\">Agrivolta\u00efque, non merci !<\/a><\/h1>\n<h1 style=\"text-align: center;\">Radio Zinzine, le 17 d\u00e9cembre 2022<\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/reporterre.net\/Agrivoltaisme-paysans-notre-metier-n-est-pas-de-produire-de-l-energie\">Reporterre.<\/a><\/h1>\n<h1 class=\"h1_15\" style=\"text-align: center;\"><a href=\"https:\/\/reporterre.net\/Agrivoltaisme-paysans-notre-metier-n-est-pas-de-produire-de-l-energie\">Agrivolta\u00efsme : paysans, notre m\u00e9tier n\u2019est pas de produire de l\u2019\u00e9nergie, Conf\u00e9d\u00e9ration Paysanne<\/a><\/h1>\n<h1 style=\"text-align: center;\">2 dec 2022<\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p style=\"text-align: center;\">&#8230;&#8230;&#8230;&#8230;&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<h1><\/h1>\n<h1 id=\":3ca\" class=\"hP\" style=\"text-align: center;\" tabindex=\"-1\" data-thread-perm-id=\"thread-a:r7680547651853202349|msg-a:r3102472860686688325\" data-legacy-thread-id=\"1867a357a371be3c\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/main-basse-sur-les-Pyrenees-Orientales-1.pdf\" target=\"_blank\" rel=\"noopener\">Les cultivateurs de kilowatts font main basse sur les Pyr\u00e9n\u00e9es-Orientales,<\/a><\/h1>\n<p style=\"text-align: center;\"><strong>version longue du second article pour l&rsquo;Empaill\u00e9 \u00ab\u00a0Tout le monde d\u00e9teste Sun&rsquo; agri\u00a0\u00bb<\/strong><\/p>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/lempaille.fr\/tout-le-monde-deteste-sun-agri\" target=\"_blank\" rel=\"noopener\"><strong>Tout le monde d\u00e9teste Sun&rsquo;Agri,<\/strong><\/a><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/lempaille.fr\/tout-le-monde-deteste-sun-agri\" target=\"_blank\" rel=\"noopener\"><strong> journal l&rsquo;Empaill\u00e9, n.8, hiver 2022-2023<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 class=\"entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/lempaille.fr\/contre-lagrivoltaisme-lautonomie-paysanne\" target=\"_blank\" rel=\"noopener\"><strong>Contre l\u2019agrivolta\u00efsme, l\u2019autonomie paysanne,<\/strong><\/a><\/h1>\n<h1 class=\"entry-title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/lempaille.fr\/contre-lagrivoltaisme-lautonomie-paysanne\" target=\"_blank\" rel=\"noopener\"> journal L&rsquo;Empaill\u00e9, automne 2022<\/a><\/strong><\/h1>\n<p style=\"text-align: center;\">Article cit\u00e9 par M\u00e9diapart <a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Energies-renouvelables-les-panneaux-solaires-sur-des-terres-agric...-Mediapart.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Energies-renouvelables-les-panneaux-solaires-sur-des-terres-agric&#8230;-Mediapart.pdf<\/a><\/p>\n<p style=\"text-align: center;\">ou ici<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/article-mediapart-agrivolt.odt\">https:\/\/ccaves.org\/blog\/wp-content\/uploads\/article-mediapart-agrivolt.odt<\/a><\/p>\n<h1 style=\"text-align: center;\"><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.francetvinfo.fr\/economie\/emploi\/metiers\/agriculture\/panneaux-solaires-les-terres-agricoles-tres-sollicitees_5467542.html\" target=\"_blank\" rel=\"noopener\"><strong>France 2, journal de 20h , 9 nov.2022<\/strong><\/a><\/h1>\n<h1 class=\"c-title \" style=\"text-align: center;\"><a href=\"https:\/\/www.francetvinfo.fr\/economie\/emploi\/metiers\/agriculture\/panneaux-solaires-les-terres-agricoles-tres-sollicitees_5467542.html\" target=\"_blank\" rel=\"noopener\"><strong>Panneaux solaires :\u00a0les terres agricoles tr\u00e8s sollicit\u00e9es<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\">&#8230;&#8230;&#8230;&#8230;<\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.radiofrance.fr\/franceinter\/podcasts\/expression-directe\/expression-directe-du-samedi-29-octobre-2022-5595340\" target=\"_blank\" rel=\"noopener\"><strong>France Inter et France Bleu, Expression directe,<\/strong><\/a><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.radiofrance.fr\/franceinter\/podcasts\/expression-directe\/expression-directe-du-samedi-29-octobre-2022-5595340\" target=\"_blank\" rel=\"noopener\"><strong> Conf\u00e9d\u00e9ration Paysanne, 29 octobre 2022<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&#8230;&#8230;&#8230;..<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Le Canard Enchain\u00e9 le 20 juillet 2022<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Canard-Enchaine-20-07-22-.pdf\" target=\"_blank\" rel=\"noopener\"><strong>\u00ab\u00a0Les campagnes tombent dans le panneau\u00a0\u00bb<\/strong><\/a><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 class=\"crayon article-titre-91 entry-title\" style=\"text-align: center;\"><a href=\"https:\/\/chez.renart.info\/?La-Troisieme-revolution-industrielle-des-Mulliez-artificialise-la-vie-la-vraie\" target=\"_blank\" rel=\"noopener\"><strong>La Troisi\u00e8me r\u00e9volution industrielle des Mulliez artificialise la vie (la vraie).<\/strong><\/a><\/h1>\n<h1 style=\"text-align: center;\"><strong>Chez Renart.<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Le Petit journal le 4 juin 2022<\/strong><\/h1>\n<h1 class=\"amp-wp-title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www-lepetitjournal-net.cdn.ampproject.org\/v\/s\/www.lepetitjournal.net\/12-aveyron\/2022\/06\/04\/voltalia-un-industriel-a-la-campagne\/amp\/?amp_gsa=1&amp;amp_js_v=a9&amp;usqp=mq331AQKKAFQArABIIACAw%3D%3D#amp_tf=Source%C2%A0%3A%20%251%24s&amp;aoh=16546219088895&amp;referrer=https%3A%2F%2Fwww.google.com&amp;ampshare=https%3A%2F%2Fwww.lepetitjournal.net%2F12-aveyron%2F2022%2F06%2F04%2Fvoltalia-un-industriel-a-la-campagne%2F\" target=\"_blank\" rel=\"noopener\">\u00ab Voltalia, un industriel \u00e0 la campagne \u00bb<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Le Petit Journal, le 22 mai<\/strong><\/h1>\n<h2 class=\"entry-title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www.lepetitjournal.net\/12-aveyron\/2022\/05\/22\/premier-revers-de-voltalia-mulliez-pierre-lapeyre-la-panouse\/#gsc.tab=0\" target=\"_blank\" rel=\"noopener\">PREMIER REVERS DE VOLTALIA-MULLIEZ-PIERRE LAPEYRE-LA PANOUSE !<\/a><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>La Lettre M, 26 avril 2022<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"http:\/\/www.lalettrem.fr\/actualites\/un-projet-photovoltaique-retire-en-aveyron\" target=\"_blank\" rel=\"noopener\">Un projet photovolta\u00efque retir\u00e9 en Aveyron<\/a><\/strong><\/h1>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/actu.fr\/societe\/aveyron-un-grand-projet-de-centrale-photovoltaique-retire-sur-le-causse-comtal_49914676.html\" target=\"_blank\" rel=\"noopener\">Actu.fr, 6 avril 2022. Aveyron. Un grand projet de centrale photovolta\u00efque retir\u00e9 sur le causse Comtal<\/a><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.centrepresseaveyron.fr\/2022\/03\/28\/photovoltaique-lun-des-trois-projets-du-causse-comtal-abandonne-10199229.php\" target=\"_blank\" rel=\"noopener\">Centre Presse 28 mars 2022<\/a><\/strong><\/h1>\n<h1 class=\"article-full__title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www.centrepresseaveyron.fr\/2022\/03\/28\/photovoltaique-lun-des-trois-projets-du-causse-comtal-abandonne-10199229.php\" target=\"_blank\" rel=\"noopener\">Photovolta\u00efque : l&rsquo;un des trois projets du Causse comtal abandonn\u00e9<\/a><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/france3-regions.francetvinfo.fr\/occitanie\/aveyron\/rodez\/aveyron-un-projet-d-installation-de-panneaux-photovoltaiques-retire-sur-le-causse-comtal-2512472.html\" target=\"_blank\" rel=\"noopener\">France 3 Occitanie 25 mars 2022<\/a><\/strong><\/h1>\n<h1 class=\"headArticle__title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/france3-regions.francetvinfo.fr\/occitanie\/aveyron\/rodez\/aveyron-un-projet-d-installation-de-panneaux-photovoltaiques-retire-sur-le-causse-comtal-2512472.html\" target=\"_blank\" rel=\"noopener\">Aveyron : un projet d&rsquo;installation de panneaux photovolta\u00efques retir\u00e9 sur le Causse-Comtal<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/vendredi-18-fevrier-2022-radio-zinzine.mp3\" target=\"_blank\" rel=\"noopener\">Radio Zinzine, le 18 f\u00e9vrier 2022<\/a><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 class=\"article-full__title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www.ladepeche.fr\/2022\/01\/07\/le-developpement-des-energies-renouvelables-en-question-10031731.php\" target=\"_blank\" rel=\"noopener\">Le d\u00e9veloppement des \u00e9nergies renouvelables en question.<\/a><\/strong><\/h1>\n<h1 class=\"article-full__title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www.ladepeche.fr\/2022\/01\/07\/le-developpement-des-energies-renouvelables-en-question-10031731.php\" target=\"_blank\" rel=\"noopener\">Centre presse le 7 janvier 2022<\/a><\/strong><\/h1>\n<p style=\"text-align: center;\"><strong>Article dans le quel notre communiqu\u00e9 n.6 sur la seconde motion de la Chambre D&rsquo;agriculture (motion propos\u00e9e par la Conf\u00e9d\u00e9ration Paysanne) est enfin \u00e9voqu\u00e9.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.cfmradio.fr\/de-grands-champs-de-panneaux-solaires-au-sol-en-aveyron-\" target=\"_blank\" rel=\"noopener\">CFM-rodez. De grands champs de panneaux solaires au sol en Aveyron ?<\/a><\/strong><\/h1>\n<p class=\"desc mainDesc\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www.cfmradio.fr\/de-grands-champs-de-panneaux-solaires-au-sol-en-aveyron-\">Les opposants \u00e0 plusieurs projets de grands parcs de panneaux solaires en Aveyron son venu rencontrer le pr\u00e9sident du conseil d\u00e9partemental il y \u00e0 quelques jours.<\/a><\/strong><\/p>\n<p class=\"desc\" style=\"text-align: center;\"><strong>Invit\u00e9(s) : Christian Roqueirol, membre de la conf\u00e9d\u00e9ration paysanne ; Lo\u00efc Santiago, membre du collectif de r\u00e9flexion citoyenne sur le photovolta\u00efque du Causse Comtal<\/strong><\/p>\n<p class=\"desc collaborateur\" style=\"text-align: center;\"><strong>Pr\u00e9sent\u00e9 par David Dumont,<\/strong><br \/>\n<strong>CFM\u00a0rodez<\/strong><\/p>\n<p class=\"date\" style=\"text-align: center;\"><strong>25 Novembre 2021<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/lepoing.net\/encense-au-corum-de-montpellier-le-capitalisme-vert-ravage-les-causses-daveyron\/\" target=\"_blank\" rel=\"noopener\">Article Le Poing-1er octobre 2021<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/lepoing.net\/encense-au-corum-de-montpellier-le-capitalisme-vert-ravage-les-causses-daveyron\/\" target=\"_blank\" rel=\"noopener\">Encens\u00e9 au Corum de Montpellier, le capitalisme vert ravage les causses d\u2019Aveyron<\/a><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Premi\u00e8re victoire\u00a0:<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong>Salles-la-Source d\u00e9lib\u00e8re contre les 3 projets industriels de parcs de panneaux photovolta\u00efques sur le Causse Comtal.<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong>La d\u00e9cence exige qu&rsquo;AKUO s&rsquo;en aille.<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.centrepresseaveyron.fr\/2021\/07\/17\/projets-de-parcs-photovoltaiques-sur-le-causse-comtal-salles-la-source-se-prononce-contre-9677750.php\" target=\"_blank\" rel=\"noopener\">\u00a0ici dans Centre Presse<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.lepetitjournal.net\/12-aveyron\/2021\/08\/22\/le-collectif-de-reflexion-citoyenne-sur-le-photovoltaique-du-causse-comtal\/#gsc.tab=0\" target=\"_blank\" rel=\"noopener\">ici dans Le Petit journal le 22 aout 2021<\/a><\/strong><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/france3-regions.francetvinfo.fr\/occitanie\/aveyron\/rodez\/aveyron-la-commune-de-salles-la-source-s-oppose-a-son-tour-au-projet-de-parcs-photovoltaiques-sur-le-causse-comtal-2204860.html\" target=\"_blank\" rel=\"noopener\">Et ici sur France 3 Occitanie<\/a><\/strong><\/h1>\n<h1 id=\"mainContent\" class=\"title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/france3-regions.francetvinfo.fr\/occitanie\/aveyron\/rodez\/aveyron-la-commune-de-salles-la-source-s-oppose-a-son-tour-au-projet-de-parcs-photovoltaiques-sur-le-causse-comtal-2204860.html\" target=\"_blank\" rel=\"noopener\">Aveyron : la commune de Salles-la-Source s\u2019oppose \u00e0 son tour au projet de parcs photovolta\u00efques sur le Causse Comtal<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Le Petit Journal, 11 juillet 2021<\/strong><\/h1>\n<h2 class=\"entry-title\" style=\"text-align: center;\"><strong><a href=\"https:\/\/www.lepetitjournal.net\/12-aveyron\/2021\/07\/11\/contre-les-3-projets-industriels-de-parcs-de-panneaux-photovoltaiques\/#gsc.tab=0\" target=\"_blank\" rel=\"noopener\">CONTRE LES 3 PROJETS INDUSTRIELS DE PARCS DE PANNEAUX PHOTOVOLTA\u00cfQUES<\/a><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 class=\"article-full__title\" style=\"text-align: center;\"><strong>Trois projets de parcs photovolta\u00efques sur le Causse comtal, le 11 mars 2021<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.centrepresseaveyron.fr\/2021\/03\/10\/trois-projets-de-parcs-photovoltaiques-sur-le-causse-comtal-9419440.php\" target=\"_blank\" rel=\"noopener\">Lire ici sur Centre Presse<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.ladepeche.fr\/2021\/03\/11\/trois-projets-de-parcs-photovoltaiques-sur-le-causse-comtal-9420135.php\" target=\"_blank\" rel=\"noopener\">Lire ici sur La D\u00e9p\u00eache<\/a><\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Parcs-photovoltaiques.jpg\" target=\"_blank\" rel=\"noopener\">Et ici en version gratuite<\/a><\/strong><\/h1>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\"><strong>Le 1er mars 2021<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><strong><a href=\"https:\/\/www.radiototem.net\/quercy-rouergue\/8324-3-projets-de-champs-photovoltaiques-sur-le-causse-comtal-a-l-etude\" target=\"_blank\" rel=\"noopener\">Radio Totem interroge notre collectif, la Conf\u00e9d\u00e9ration Paysanne, la LPO <\/a><\/strong><\/h1>\n<h1><\/h1>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1 class=\"article-full__title\" style=\"text-align: center;\"><strong>Une de Centre Presse le 15 ao\u00fbt 2020<\/strong><\/h1>\n<h1 class=\"article-full__title\" style=\"text-align: center;\"><strong>Photovolta\u00efque : les investisseurs s\u2019int\u00e9ressent au causse Comtal<\/strong><\/h1>\n<h1 style=\"text-align: center;\"><a href=\"https:\/\/www.centrepresseaveyron.fr\/2020\/08\/14\/photovoltaique-les-investisseurs-sinteressent-au-causse-comtal-9020434.php\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Lire ici\u00a0<\/strong><\/a><\/h1>\n<p class=\"article-full__chapo\" style=\"text-align: center;\">Des projets de parcs photovolta\u00efques g\u00e9ants sont \u00e0 l\u2019\u00e9tude \u00e0 Salles-la-Source notamment. Un collectif d\u2019opposants d\u00e9nonce le manque d\u2019information et demande aux \u00e9lus d\u2019organiser une consultation citoyenne.<\/p>\n<div class=\"article-full__body-content article-paywall p402_premium\" style=\"text-align: center;\">\n<p>Aucun champ agricole, de causses ou de zones naturelles sensibles ne figure parmi la liste des pr\u00e8s de 20 000 sites clairement identifi\u00e9s par l\u2019Ademe (lire par ailleurs), pour id\u00e9alement exploiter les rayons de l\u2019astre solaire. Quelque part, cela semble logique. Surtout, lorsque l\u2019on conna\u00eet la valeur des terres arables ; de plus en plus rares et de plus en plus convoit\u00e9es. Le causse et les zones naturelles sensibles repr\u00e9sentent quant \u00e0 eux une haute valeur patrimoniale, environnementale et\/ou touristique.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Articles du collectif ou articles \u00e9crits par nos membres ou pour lesquels ils ont particip\u00e9 &nbsp; &nbsp; &nbsp; La Trousse<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[55],"tags":[],"class_list":["post-4280","post","type-post","status-publish","format-standard","hentry","category-photovoltaique-causse-comtal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>medias photovolta\u00efque causse comtal - CCAVES<\/title>\n<meta name=\"description\" content=\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"medias photovolta\u00efque causse comtal - CCAVES\" \/>\n<meta property=\"og:description\" content=\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/\" \/>\n<meta property=\"og:site_name\" content=\"CCAVES\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-25T11:09:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T13:40:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201\" \/>\n<meta name=\"author\" content=\"collectifvallon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"collectifvallon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/\"},\"author\":{\"name\":\"collectifvallon\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/person\\\/d776b30895ca193bcb27a7923f266e29\"},\"headline\":\"medias photovolta\u00efque causse comtal\",\"datePublished\":\"2021-10-25T11:09:59+00:00\",\"dateModified\":\"2023-09-04T13:40:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/\"},\"wordCount\":843,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revuesilence.net\\\/local\\\/cache-vignettes\\\/L425xH600\\\/rubon510-d5ded.jpg?1690209201\",\"articleSection\":[\"photovolta\u00efque causse comtal\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/\",\"name\":\"medias photovolta\u00efque causse comtal - CCAVES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.revuesilence.net\\\/local\\\/cache-vignettes\\\/L425xH600\\\/rubon510-d5ded.jpg?1690209201\",\"datePublished\":\"2021-10-25T11:09:59+00:00\",\"dateModified\":\"2023-09-04T13:40:36+00:00\",\"description\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.revuesilence.net\\\/local\\\/cache-vignettes\\\/L425xH600\\\/rubon510-d5ded.jpg?1690209201\",\"contentUrl\":\"https:\\\/\\\/www.revuesilence.net\\\/local\\\/cache-vignettes\\\/L425xH600\\\/rubon510-d5ded.jpg?1690209201\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/medias-photovoltaique-causse-comtal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"medias photovolta\u00efque causse comtal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\",\"name\":\"CCAVES\",\"description\":\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\"},\"alternateName\":\"Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\",\"name\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"alternateName\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/Oedicneme-criard-IMP-1024x631.png\",\"contentUrl\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/Oedicneme-criard-IMP-1024x631.png\",\"width\":1024,\"height\":631,\"caption\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/person\\\/d776b30895ca193bcb27a7923f266e29\",\"name\":\"collectifvallon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g\",\"caption\":\"collectifvallon\"},\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/author\\\/loic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"medias photovolta\u00efque causse comtal - CCAVES","description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/","og_locale":"fr_FR","og_type":"article","og_title":"medias photovolta\u00efque causse comtal - CCAVES","og_description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","og_url":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/","og_site_name":"CCAVES","article_published_time":"2021-10-25T11:09:59+00:00","article_modified_time":"2023-09-04T13:40:36+00:00","og_image":[{"url":"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201","type":"","width":"","height":""}],"author":"collectifvallon","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"collectifvallon","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#article","isPartOf":{"@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/"},"author":{"name":"collectifvallon","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/person\/d776b30895ca193bcb27a7923f266e29"},"headline":"medias photovolta\u00efque causse comtal","datePublished":"2021-10-25T11:09:59+00:00","dateModified":"2023-09-04T13:40:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/"},"wordCount":843,"commentCount":1,"publisher":{"@id":"https:\/\/ccaves.org\/blog\/#organization"},"image":{"@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201","articleSection":["photovolta\u00efque causse comtal"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/","url":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/","name":"medias photovolta\u00efque causse comtal - CCAVES","isPartOf":{"@id":"https:\/\/ccaves.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#primaryimage"},"image":{"@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201","datePublished":"2021-10-25T11:09:59+00:00","dateModified":"2023-09-04T13:40:36+00:00","description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","breadcrumb":{"@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#primaryimage","url":"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201","contentUrl":"https:\/\/www.revuesilence.net\/local\/cache-vignettes\/L425xH600\/rubon510-d5ded.jpg?1690209201"},{"@type":"BreadcrumbList","@id":"https:\/\/ccaves.org\/blog\/medias-photovoltaique-causse-comtal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ccaves.org\/blog\/"},{"@type":"ListItem","position":2,"name":"medias photovolta\u00efque causse comtal"}]},{"@type":"WebSite","@id":"https:\/\/ccaves.org\/blog\/#website","url":"https:\/\/ccaves.org\/blog\/","name":"CCAVES","description":"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","publisher":{"@id":"https:\/\/ccaves.org\/blog\/#organization"},"alternateName":"Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccaves.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ccaves.org\/blog\/#organization","name":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","alternateName":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","url":"https:\/\/ccaves.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","contentUrl":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","width":1024,"height":631,"caption":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9"},"image":{"@id":"https:\/\/ccaves.org\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/person\/d776b30895ca193bcb27a7923f266e29","name":"collectifvallon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g","caption":"collectifvallon"},"url":"https:\/\/ccaves.org\/blog\/author\/loic\/"}]}},"_links":{"self":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/4280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/comments?post=4280"}],"version-history":[{"count":31,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/4280\/revisions"}],"predecessor-version":[{"id":5095,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/4280\/revisions\/5095"}],"wp:attachment":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/media?parent=4280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/categories?post=4280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/tags?post=4280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}