{"id":4366,"date":"2021-11-25T18:22:53","date_gmt":"2021-11-25T17:22:53","guid":{"rendered":"https:\/\/ccaves.org\/blog\/?p=4366"},"modified":"2021-11-25T18:22:53","modified_gmt":"2021-11-25T17:22:53","slug":"communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal","status":"publish","type":"post","link":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/","title":{"rendered":"Communiqu\u00e9 du 24\/11\/21      Les cam\u00e9ras de Marcillac-Vallon au tribunal !"},"content":{"rendered":"<h1 align=\"CENTER\"><b>Communiqu\u00e9 du 24\/11\/21<\/b><\/h1>\n<h1 align=\"CENTER\"><b>Les cam\u00e9ras de Marcillac-Vallon au tribunal\u00a0!<\/b><\/h1>\n<p>&nbsp;<\/p>\n<h2 align=\"JUSTIFY\">Le \u00ab\u00a0collectif de r\u00e9flexion citoyenne sur les cam\u00e9ras de Marcillac-Vallon\u00a0\u00bb a d\u00e9cid\u00e9 de saisir le tribunal administratif de Toulouse pour demander le d\u00e9montage des cam\u00e9ras de vid\u00e9osurveillance, fra\u00eechement install\u00e9es dans le village. En effet, la mobilisation n&rsquo;a pas suffit\u00a0: la p\u00e9tition sign\u00e9e par des milliers de personnes, les multiples banderoles accroch\u00e9es aux fa\u00e7ades des maisons, les tracts distribu\u00e9s dans toutes les boites aux lettres de Marcillac, les lettres aux \u00e9lus, les interventions en conseil municipal&#8230; Le maire de la commune a d\u00e9cid\u00e9 de passer outre. Contre une partie de la population, contre l&rsquo;opposition des d\u00e9l\u00e9gu\u00e9s de parents d&rsquo;\u00e9l\u00e8ves, contre le travail d&rsquo;\u00e9lus de sa majorit\u00e9 qui s&rsquo;\u00e9taient d\u00e9men\u00e9s pour agir contre les d\u00e9p\u00f4ts sauvages, et m\u00eame contre sa propre parole puisqu&rsquo;il avait d\u00e9cid\u00e9 en juillet d&rsquo;abandonner la pose de cam\u00e9ras \u00e0 proximit\u00e9 des poubelles.<\/h2>\n<h2 align=\"JUSTIFY\">En catimini, le maire M. P\u00e9ri\u00e9 a d\u00e9cid\u00e9 en septembre de se passer d&rsquo;une deuxi\u00e8me d\u00e9lib\u00e9ration du conseil municipal que tous et toutes attendaient, et d&rsquo;installer les cinq cam\u00e9ras pr\u00e9vues. Dor\u00e9navant, tous les habitants et les habitantes sont film\u00e9s lorsqu&rsquo;ils d\u00e9posent leurs sacs poubelles, et tous les enfants, parents et personnels scolaires sont film\u00e9s \u00e0 leurs entr\u00e9es et sorties de l&rsquo;\u00e9cole maternelle Jean Auzel. Nous continuons de penser que cette installation, \u00e0 la fois ridicule et d\u00e9l\u00e9t\u00e8re, m\u00e9rite une opposition farouche. C&rsquo;est pourquoi nous portons cela devant le tribunal qui jugera de la disproportionnalit\u00e9 de l&rsquo;installation. En m\u00eame temps nous envisageons de nouvelles actions, pour obtenir le d\u00e9montage de ces cam\u00e9ras. Aussi, et dans la mesure de nos moyens, nous emp\u00eacherons le d\u00e9veloppement d&rsquo;autres cam\u00e9ras dans Marcillac, dans le Vallon et ailleurs&#8230;<\/h2>\n<h2 align=\"JUSTIFY\">En France, des dizaines de milliers de cam\u00e9ras ont \u00e9t\u00e9 install\u00e9es ces vingt derni\u00e8res ann\u00e9es, et l&rsquo;\u00e9volution r\u00e9cente est exponentielle, allant jusqu&rsquo;\u00e0 la multiplication de ces dispositifs de surveillance dans les petites villes et villages. Elles sont l&rsquo;un des marqueurs d&rsquo;une politique fustigeant nos libert\u00e9s, et de la droitisation de notre soci\u00e9t\u00e9, tant dans les politiques mises en \u0153uvre que dans les discours. Ces cam\u00e9ras alimentent des fantasmes d\u2019ins\u00e9curit\u00e9. A force de miser sur la peur, la s\u00e9curit\u00e9, l&rsquo;individualisme et le repli sur soi, il ne faut pas s&rsquo;\u00e9tonner que l&rsquo;extr\u00eame droite pointe \u00e0 35% dans les sondages. Jamais nous ne nous r\u00e9soudrons \u00e0 cette \u00e9volution politique et sociale, et c&rsquo;est de toutes nos forces que nous continuerons de porter des valeurs de solidarit\u00e9, d&rsquo;entraide et de vivre ensemble. A la place des cam\u00e9ras, nous voulons un village vivant, o\u00f9 l&rsquo;on peut encore d\u00e9poser son enfant de quatre ans \u00e0 l&rsquo;\u00e9cole sans \u00eatre vid\u00e9o-surveill\u00e9. Pour d\u00e9fendre nos droits de citoyens, vous avez \u00e9t\u00e9 des milliers \u00e0 nous soutenir, et gr\u00e2ce \u00e0 vous nous avons r\u00e9uni plus de 3000 euros nous aidant pour les frais de justice. Que \u00e9lu.es se le tiennent pour dit, une dynamique est enclench\u00e9e. Continuons\u00a0!<\/h2>\n<h2><\/h2>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\"><b>Pour se d\u00e9fendre des cam\u00e9ras, on a besoin de vous !<\/b><\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\">Vous nous avez suivi ces derniers mois, vous nous avez soutenu<\/div>\n<div style=\"text-align: center;\">C&rsquo;est ensemble que nous avons pu faire faire entendre nos voix et nos droits!<\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\">Nous avons \u00e9t\u00e9 oblig\u00e9.e.s de porter plainte contre la mairie, la proc\u00e9dure est en cours.<\/div>\n<div style=\"text-align: center;\">Et parce que d\u00e9sormais pour d\u00e9fendre nos droits, il faut payer!!! Nous avons eu pour 2800 \u20ac d&rsquo;avocat\u00a0 sans compter le mat\u00e9riels type banderoles, tracts&#8230;<\/div>\n<div style=\"text-align: center;\">Pour rembourser nos gentils pr\u00eateurs.ses, il nous manque encore 647\u20ac.<\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\"><b>Alors peu importe le montant de votre soutien, il n&rsquo;y a pas de petits dons !\u00a0<\/b><\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\">Merci d&rsquo;avance, merci encore ! Et on vous pr\u00e9pare une prochaine action festive..:) donc \u00e0 tr\u00e8s bient\u00f4t!<\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\">Pour nous soutenir :<\/div>\n<div style=\"text-align: center;\"><\/div>\n<div style=\"text-align: center;\">&#8211; \u00a0<a href=\"https:\/\/www.leetchi.com\/fr\/c\/w3x3B4k5\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">https:\/\/www.leetchi.com\/fr\/c\/w3x3B4k5<\/a><\/div>\n<div style=\"text-align: center;\">&#8211; au p&rsquo;ti Bio, 5 all\u00e9es des rosiers, par ch\u00e8que au nom de Maitre Boda ou en esp\u00e8ces<\/div>\n<div style=\"text-align: center;\">&#8211; \u00a0au Guingois 17 place de l&rsquo;\u00e9glise, dans la boite aux lettres au milieu de la vitrine, dans enveloppe pr\u00e9cisant \u00ab\u00a0contre les cam\u00e9ras\u00a0\u00bb, d\u00e9p\u00f4t ch\u00e8que ou liquide.<\/div>\n<div style=\"text-align: center;\">&#8211; Au panier paysan selon les m\u00eames modalit\u00e9s<\/div>\n<div><\/div>\n<div><\/div>\n<p align=\"JUSTIFY\"><b>Le collectif de r\u00e9flexion citoyenne sur les cam\u00e9ras de surveillance \u00e0 Marcillac-Vallon.<\/b><\/p>\n<div><\/div>\n<div><\/div>\n<div><b>Site internet :\u00a0<\/b><a href=\"https:\/\/ccaves.org\/blog\/\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">https:\/\/ccaves.org\/blog\/<\/a><b><\/b><\/div>\n<div class=\"protonmail_signature_block\">\n<div class=\"protonmail_signature_block-user\">\n<div>Envoy\u00e9 d&rsquo;un ordinateur connect\u00e9 en filaire.<\/div>\n<\/div>\n<div><\/div>\n<div class=\"protonmail_signature_block-proton\">Sent with\u00a0<a href=\"https:\/\/protonmail.com\/\" target=\"_blank\" rel=\"noreferrer nofollow noopener\">ProtonMail<\/a>\u00a0Secure Email.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Communiqu\u00e9 du 24\/11\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal\u00a0! &nbsp; Le \u00ab\u00a0collectif de r\u00e9flexion citoyenne sur les cam\u00e9ras de Marcillac-Vallon\u00a0\u00bb<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[54],"tags":[],"class_list":["post-4366","post","type-post","status-publish","format-standard","hentry","category-cameras-de-videosurveillance-a-marcillac-vallon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Communiqu\u00e9 du 24\/11\/21   Les cam\u00e9ras de Marcillac-Vallon au tribunal ! - CCAVES<\/title>\n<meta name=\"description\" content=\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Communiqu\u00e9 du 24\/11\/21   Les cam\u00e9ras de Marcillac-Vallon au tribunal ! - CCAVES\" \/>\n<meta property=\"og:description\" content=\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/\" \/>\n<meta property=\"og:site_name\" content=\"CCAVES\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-25T17:22:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"collectifvallon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"collectifvallon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/\"},\"author\":{\"name\":\"collectifvallon\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/person\\\/d776b30895ca193bcb27a7923f266e29\"},\"headline\":\"Communiqu\u00e9 du 24\\\/11\\\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal !\",\"datePublished\":\"2021-11-25T17:22:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/\"},\"wordCount\":779,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\"},\"articleSection\":[\"Cam\u00e9ras de vid\u00e9osurveillance \u00e0 Marcillac-Vallon\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/\",\"name\":\"Communiqu\u00e9 du 24\\\/11\\\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal ! - CCAVES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#website\"},\"datePublished\":\"2021-11-25T17:22:53+00:00\",\"description\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Communiqu\u00e9 du 24\\\/11\\\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\",\"name\":\"CCAVES\",\"description\":\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\"},\"alternateName\":\"Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\",\"name\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"alternateName\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/Oedicneme-criard-IMP-1024x631.png\",\"contentUrl\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/Oedicneme-criard-IMP-1024x631.png\",\"width\":1024,\"height\":631,\"caption\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/person\\\/d776b30895ca193bcb27a7923f266e29\",\"name\":\"collectifvallon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g\",\"caption\":\"collectifvallon\"},\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/author\\\/loic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Communiqu\u00e9 du 24\/11\/21   Les cam\u00e9ras de Marcillac-Vallon au tribunal ! - CCAVES","description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/","og_locale":"fr_FR","og_type":"article","og_title":"Communiqu\u00e9 du 24\/11\/21   Les cam\u00e9ras de Marcillac-Vallon au tribunal ! - CCAVES","og_description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","og_url":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/","og_site_name":"CCAVES","article_published_time":"2021-11-25T17:22:53+00:00","og_image":[{"width":1024,"height":631,"url":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","type":"image\/png"}],"author":"collectifvallon","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"collectifvallon","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/#article","isPartOf":{"@id":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/"},"author":{"name":"collectifvallon","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/person\/d776b30895ca193bcb27a7923f266e29"},"headline":"Communiqu\u00e9 du 24\/11\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal !","datePublished":"2021-11-25T17:22:53+00:00","mainEntityOfPage":{"@id":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/"},"wordCount":779,"commentCount":0,"publisher":{"@id":"https:\/\/ccaves.org\/blog\/#organization"},"articleSection":["Cam\u00e9ras de vid\u00e9osurveillance \u00e0 Marcillac-Vallon"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/","url":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/","name":"Communiqu\u00e9 du 24\/11\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal ! - CCAVES","isPartOf":{"@id":"https:\/\/ccaves.org\/blog\/#website"},"datePublished":"2021-11-25T17:22:53+00:00","description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","breadcrumb":{"@id":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ccaves.org\/blog\/communique-du-24-11-21-les-cameras-de-marcillac-vallon-au-tribunal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ccaves.org\/blog\/"},{"@type":"ListItem","position":2,"name":"Communiqu\u00e9 du 24\/11\/21 Les cam\u00e9ras de Marcillac-Vallon au tribunal !"}]},{"@type":"WebSite","@id":"https:\/\/ccaves.org\/blog\/#website","url":"https:\/\/ccaves.org\/blog\/","name":"CCAVES","description":"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","publisher":{"@id":"https:\/\/ccaves.org\/blog\/#organization"},"alternateName":"Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccaves.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ccaves.org\/blog\/#organization","name":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","alternateName":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","url":"https:\/\/ccaves.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","contentUrl":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","width":1024,"height":631,"caption":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9"},"image":{"@id":"https:\/\/ccaves.org\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/person\/d776b30895ca193bcb27a7923f266e29","name":"collectifvallon","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fb252f144334c6af21b3edf929630a011715a9a10cebad3a3dc971a32be991db?s=96&d=mm&r=g","caption":"collectifvallon"},"url":"https:\/\/ccaves.org\/blog\/author\/loic\/"}]}},"_links":{"self":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/4366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/comments?post=4366"}],"version-history":[{"count":1,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/4366\/revisions"}],"predecessor-version":[{"id":4367,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/4366\/revisions\/4367"}],"wp:attachment":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/media?parent=4366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/categories?post=4366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/tags?post=4366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}