{"id":5826,"date":"2026-02-10T14:15:04","date_gmt":"2026-02-10T13:15:04","guid":{"rendered":"https:\/\/ccaves.org\/blog\/?p=5826"},"modified":"2026-02-10T14:19:54","modified_gmt":"2026-02-10T13:19:54","slug":"les-energies-renouvelables","status":"publish","type":"post","link":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/","title":{"rendered":"LES \u00c9NERGIES RENOUVELABLES"},"content":{"rendered":"<p>Lien vers le pdf : <a href=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Les-energies-renouvelables-Vf1.pdf\">Les \u00e9nergies renouvelables-Vf1<\/a><\/p>\n<h2><strong><span style=\"color: #339966\">Qu\u2019est-ce que c\u2019est ?<\/span> <\/strong><\/h2>\n<p>Les \u00e9nergies renouvelables sont des sources d\u2019\u00e9nergie qui se renouvellent naturellement \u00e0 l\u2019\u00e9chelle humaine. Contrairement aux \u00e9nergies fossiles, elles sont pratiquement in\u00e9puisables.<\/p>\n<p>Les principales sources comprennent :<\/p>\n<h3><span style=\"color: #339966\">\u00c9nergie solaire<\/span><\/h3>\n<p>L\u2019\u00e9nergie solaire photovolta\u00efque est l&rsquo;une des technologies renouvelables la plus dynamique. Des pays comme la Chine, les \u00c9tats-Unis, l&rsquo;Inde et l\u2019Allemagne ont massivement investi dans cette technologie. Les progr\u00e8s technologiques ont permis une baisse significative des co\u00fbts de production.<\/p>\n<h3><span style=\"color: #339966\">\u00c9nergie \u00e9olienne<\/span><\/h3>\n<p>L\u2019\u00e9nergie \u00e9olienne terrestre et offshore continue de cro\u00eetre rapidement. L\u2019Europe, notamment le Danemark, l&rsquo;Allemagne et le Royaume-Uni, ainsi que les \u00c9tats-Unis et la Chine, dominent le secteur. Les parcs \u00e9oliens offshore se d\u00e9veloppent (ex : Le parc de Saint-Brieuc permet l\u2019alimentation \u00e9lectrique de 835 000 personnes. La puissance du parc correspond \u00e0\u00a0 environ la moiti\u00e9 de celle d\u2019un r\u00e9acteur nucl\u00e9aire).<\/p>\n<h3><span style=\"color: #339966\">\u00c9nergie hydraulique<\/span><\/h3>\n<p>L\u2019\u00e9nergie hydraulique reste la principale source d\u2019\u00e9nergie renouvelable dans le monde, avec une forte pr\u00e9sence en Am\u00e9rique du Sud, en Asie et en Europe. Cependant, son d\u00e9veloppement est limit\u00e9 par des contraintes environnementales\u00a0 g\u00e9ographiques.<\/p>\n<h3><span style=\"color: #339966\">Biomasse<\/span><\/h3>\n<p>Ensemble des mati\u00e8res organiques pouvant devenir sources d\u2019\u00e9nergie\u00a0: le bois, le biogaz apr\u00e8s m\u00e9thanisation et les biocarburants, carburants de substitution g\u00e9n\u00e9ralement incorpor\u00e9s dans les carburants d\u2019origine fossile.<\/p>\n<h3><span style=\"color: #339966\">G\u00e9othermie<\/span><\/h3>\n<p>La g\u00e9othermie (chaleur du noyau terrestre) est exploit\u00e9e dans des r\u00e9gions volcaniques comme l\u2019Islande, le Kenya et les Philippines.<\/p>\n<p>En 2023, la consommation primaire d&rsquo;\u00e9nergies renouvelables en France repr\u00e9sente environ <strong>14 %<\/strong> de la consommation totale, r\u00e9partie comme suit :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5828\" src=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1-300x191.jpg\" alt=\"\" width=\"610\" height=\"388\" srcset=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1-300x191.jpg 300w, https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1.jpg 668w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/p>\n<p>Les \u00e9nergies renouvelables sont utilis\u00e9es principalement dans 3 domaines :<\/p>\n<p><span style=\"color: #0000ff\"><strong>\u00a0 \u00a0 \u00a0<\/strong><\/span><\/p>\n<p><span style=\"color: #0000ff\"><strong>Chauffage<\/strong> <strong>50%<\/strong><\/span> (bois, biogaz, autres)<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5830 alignleft\" src=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr2.jpg\" alt=\"\" width=\"264\" height=\"230\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000\"><strong>\u00c9lectricit\u00e9<\/strong> <strong>38%<\/strong> <\/span>(hydro\u00e9lectrique,<\/p>\n<p>\u00e9olien, solaire photovolta\u00efque)<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #99cc00\"><strong>D\u00e9placement <\/strong><strong>12 %<\/strong> <\/span>(biocarburant)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Les \u00e9nergies renouvelables jouent un r\u00f4le crucial dans la lutte contre le changement climatique et la transition \u00e9nerg\u00e9tique mondiale. Elles offrent une alternative moins polluante et durable aux sources d\u2019\u00e9nergie fossiles, responsables de l\u2019\u00e9mission massive de gaz \u00e0 effet de serre.<\/p>\n<h2><span style=\"color: #99cc00\">B\u00e9n\u00e9fices des \u00e9nergies renouvelables<\/span><\/h2>\n<p>Les \u00e9nergies renouvelables pr\u00e9sentent de nombreux avantages :<\/p>\n<p><strong>R\u00e9duction des \u00e9missions de gaz \u00e0 effet de serre<\/strong> : elles permettent de lutter efficacement contre le changement climatique.<\/p>\n<p><strong>Ind\u00e9pendance \u00e9nerg\u00e9tique<\/strong> : les ressources renouvelables sont disponibles localement, r\u00e9duisant ainsi la d\u00e9pendance aux importations.<\/p>\n<p><strong>Cr\u00e9ation d\u2019emplois<\/strong> : le d\u00e9veloppement de ces technologies g\u00e9n\u00e8re de nombreuses opportunit\u00e9s \u00e9conomiques.<\/p>\n<p><strong>Pr\u00e9servation des ressources naturelles<\/strong> : elles contribuent \u00e0 une exploitation plus durable de l\u2019environnement.<\/p>\n<p>Toutefois ce d\u00e9veloppement doit r\u00e9pondre \u00e0 quelques principes.<\/p>\n<p>La r\u00e9duction de notre consommation d\u2019\u00e9nergie doit \u00eatre prioritaire.<\/p>\n<p>Les terres agricoles doivent servir en priorit\u00e9 \u00e0 l\u2019alimentation. Attention au lobby de l\u2019agrivolta\u00efsme, des biocarburants et des giga m\u00e9thaniseurs.<\/p>\n<p>Il faut prendre en compte l\u2019impact environnemental : la construction de barrages ou de parcs \u00e9oliens affecter les \u00e9cosyst\u00e8mes locaux.<\/p>\n<p>Il faut prendre en compte les effets indirects comme l\u2019extraction de terres rares<\/p>\n<h2><strong><span style=\"color: #99cc00\">Nos propositions<\/span> <\/strong><\/h2>\n<p>La lutte contre le r\u00e9chauffement climatique impose de r\u00e9duire fortement notre consommation d\u2019\u00e9nergies fossiles et d\u2019augmenter la part des \u00e9nergies renouvelables tout en respectant une certaine sobri\u00e9t\u00e9 de leurs usages.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lien vers le pdf : Les \u00e9nergies renouvelables-Vf1 Qu\u2019est-ce que c\u2019est ? Les \u00e9nergies renouvelables sont des sources d\u2019\u00e9nergie qui<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[52],"tags":[],"class_list":["post-5826","post","type-post","status-publish","format-standard","hentry","category-comite-causse-comtal-assocazition-agreee-environnement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LES \u00c9NERGIES RENOUVELABLES - CCAVES<\/title>\n<meta name=\"description\" content=\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LES \u00c9NERGIES RENOUVELABLES - CCAVES\" \/>\n<meta property=\"og:description\" content=\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/\" \/>\n<meta property=\"og:site_name\" content=\"CCAVES\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T13:15:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T13:19:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"668\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/\"},\"author\":{\"name\":\"daniel\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/person\\\/ccf12d731a686b973211158c190e2ee8\"},\"headline\":\"LES \u00c9NERGIES RENOUVELABLES\",\"datePublished\":\"2026-02-10T13:15:04+00:00\",\"dateModified\":\"2026-02-10T13:19:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/\"},\"wordCount\":546,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/enr1-300x191.jpg\",\"articleSection\":[\"Comite Causse Comtal association agr\u00e9\u00e9e environnement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/\",\"name\":\"LES \u00c9NERGIES RENOUVELABLES - CCAVES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/enr1-300x191.jpg\",\"datePublished\":\"2026-02-10T13:15:04+00:00\",\"dateModified\":\"2026-02-10T13:19:54+00:00\",\"description\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/enr1.jpg\",\"contentUrl\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/enr1.jpg\",\"width\":668,\"height\":426},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/les-energies-renouvelables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LES \u00c9NERGIES RENOUVELABLES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\",\"name\":\"CCAVES\",\"description\":\"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\"},\"alternateName\":\"Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#organization\",\"name\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"alternateName\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/Oedicneme-criard-IMP-1024x631.png\",\"contentUrl\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/wp-content\\\/uploads\\\/Oedicneme-criard-IMP-1024x631.png\",\"width\":1024,\"height\":631,\"caption\":\"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/#\\\/schema\\\/person\\\/ccf12d731a686b973211158c190e2ee8\",\"name\":\"daniel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/919d31cd4e831d3c71a70d6f6f27c5a0936b963bcf54dcfb13ad43c70db28476?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/919d31cd4e831d3c71a70d6f6f27c5a0936b963bcf54dcfb13ad43c70db28476?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/919d31cd4e831d3c71a70d6f6f27c5a0936b963bcf54dcfb13ad43c70db28476?s=96&d=mm&r=g\",\"caption\":\"daniel\"},\"url\":\"https:\\\/\\\/ccaves.org\\\/blog\\\/author\\\/daniel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LES \u00c9NERGIES RENOUVELABLES - CCAVES","description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/","og_locale":"fr_FR","og_type":"article","og_title":"LES \u00c9NERGIES RENOUVELABLES - CCAVES","og_description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","og_url":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/","og_site_name":"CCAVES","article_published_time":"2026-02-10T13:15:04+00:00","article_modified_time":"2026-02-10T13:19:54+00:00","og_image":[{"width":668,"height":426,"url":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1.jpg","type":"image\/jpeg"}],"author":"daniel","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"daniel","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#article","isPartOf":{"@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/"},"author":{"name":"daniel","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/person\/ccf12d731a686b973211158c190e2ee8"},"headline":"LES \u00c9NERGIES RENOUVELABLES","datePublished":"2026-02-10T13:15:04+00:00","dateModified":"2026-02-10T13:19:54+00:00","mainEntityOfPage":{"@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/"},"wordCount":546,"commentCount":1,"publisher":{"@id":"https:\/\/ccaves.org\/blog\/#organization"},"image":{"@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#primaryimage"},"thumbnailUrl":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1-300x191.jpg","articleSection":["Comite Causse Comtal association agr\u00e9\u00e9e environnement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/","url":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/","name":"LES \u00c9NERGIES RENOUVELABLES - CCAVES","isPartOf":{"@id":"https:\/\/ccaves.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#primaryimage"},"image":{"@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#primaryimage"},"thumbnailUrl":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1-300x191.jpg","datePublished":"2026-02-10T13:15:04+00:00","dateModified":"2026-02-10T13:19:54+00:00","description":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","breadcrumb":{"@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#primaryimage","url":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1.jpg","contentUrl":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/enr1.jpg","width":668,"height":426},{"@type":"BreadcrumbList","@id":"https:\/\/ccaves.org\/blog\/les-energies-renouvelables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ccaves.org\/blog\/"},{"@type":"ListItem","position":2,"name":"LES \u00c9NERGIES RENOUVELABLES"}]},{"@type":"WebSite","@id":"https:\/\/ccaves.org\/blog\/#website","url":"https:\/\/ccaves.org\/blog\/","name":"CCAVES","description":"Plateforme d&#039;\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","publisher":{"@id":"https:\/\/ccaves.org\/blog\/#organization"},"alternateName":"Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccaves.org\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ccaves.org\/blog\/#organization","name":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","alternateName":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9","url":"https:\/\/ccaves.org\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","contentUrl":"https:\/\/ccaves.org\/blog\/wp-content\/uploads\/Oedicneme-criard-IMP-1024x631.png","width":1024,"height":631,"caption":"Plateforme d'\u00e9changes et de Coordination des Collectifs et Associations Volontaires en Environnement Sant\u00e9 et Soci\u00e9t\u00e9"},"image":{"@id":"https:\/\/ccaves.org\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ccaves.org\/blog\/#\/schema\/person\/ccf12d731a686b973211158c190e2ee8","name":"daniel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/919d31cd4e831d3c71a70d6f6f27c5a0936b963bcf54dcfb13ad43c70db28476?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/919d31cd4e831d3c71a70d6f6f27c5a0936b963bcf54dcfb13ad43c70db28476?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/919d31cd4e831d3c71a70d6f6f27c5a0936b963bcf54dcfb13ad43c70db28476?s=96&d=mm&r=g","caption":"daniel"},"url":"https:\/\/ccaves.org\/blog\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/5826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/comments?post=5826"}],"version-history":[{"count":3,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/5826\/revisions"}],"predecessor-version":[{"id":5833,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/posts\/5826\/revisions\/5833"}],"wp:attachment":[{"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/media?parent=5826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/categories?post=5826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccaves.org\/blog\/wp-json\/wp\/v2\/tags?post=5826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}